{"id":126635,"date":"2026-07-15T11:56:13","date_gmt":"2026-07-15T09:56:13","guid":{"rendered":"https:\/\/www.lasalle.org\/?p=126635"},"modified":"2026-07-15T12:12:49","modified_gmt":"2026-07-15T10:12:49","slug":"nomination-du-frere-visiteur-auxiliaire-du-district-de-lwanga","status":"publish","type":"post","link":"https:\/\/www.lasalle.org\/fr\/nomination-du-frere-visiteur-auxiliaire-du-district-de-lwanga\/","title":{"rendered":"Nomination du Fr\u00e8re Visiteur auxiliaire du District de Lwanga"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-top-right\"><a href=\"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/posts\/126635?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.lasalle.org\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"T\u00e9l\u00e9charger le PDF\" \/><span class=\"pdfprnt-button-title pdfprnt-button-pdf-title\">PDF<\/span><\/a><a href=\"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/posts\/126635?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.lasalle.org\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Contenu imprim\u00e9\" \/><span class=\"pdfprnt-button-title pdfprnt-button-print-title\">PRINT<\/span><\/a><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><b>Fr\u00e8re Armin Luistro, Sup\u00e9rieur G\u00e9n\u00e9ral des Fr\u00e8res des \u00c9coles Chr\u00e9tiennes,\u00a0a nomm\u00e9 Fr\u00e8re Moses Abunya Visiteur auxiliaire du District de Lwanga. <\/b><span style=\"font-weight: 400;\">Son mandat durera quatre ans, aux c\u00f4t\u00e9s du\u00a0<\/span><a href=\"https:\/\/www.lasalle.org\/fr\/nomination-du-frere-visiteur-du-district-de-lwanga-pour-un-second-mandat\/\"><span style=\"font-weight: 400;\">Fr\u00e8re Betre Fisseha, Visiteur du District<\/span><\/a><span style=\"font-weight: 400;\">,\u00a0du 10 juillet 2026 au 30 juin 2030.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le Fr\u00e8re Akpoughul-Abunya Msughter Moses est originaire de Naka, dans le gouvernorat de Gwer West, dans l\u2019\u00c9tat de Benue, au Nigeria. Il est entr\u00e9 chez les Fr\u00e8res en 1995 et a prononc\u00e9 ses v\u0153ux perp\u00e9tuels le 29 octobre 2005.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De 2005 \u00e0 2011, il a \u00e9t\u00e9 recteur du s\u00e9minaire St Pierre \u00e0 Yola, au Nigeria. Le Fr\u00e8re a \u00e9t\u00e9 le d\u00e9l\u00e9gu\u00e9 des Pionniers d\u2019Afrique au Conseil international des jeunes lasalliens, pendant quatre ans.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il a obtenu le titre de Responsable p\u00e9dagogique dans le programme de ma\u00eetrise en \u00e9ducation. Il est titulaire d\u2019une licence en \u00e9ducation de l\u2019universit\u00e9 St Mary\u2019s, dans le Minnesota (\u00c9tats-Unis). Il est titulaire d\u2019un master en leadership \u00e9ducatif de l\u2019Universit\u00e9 des Fr\u00e8res de Memphis, Tennessee, aux \u00c9tats-Unis, et d\u2019un doctorat en leadership \u00e9ducatif de l\u2019Universit\u00e9 Lewis.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous adressons nos f\u00e9licitations et nos meilleurs v\u0153ux au Fr\u00e8re Moses pour la mission et la responsabilit\u00e9 qui lui ont \u00e9t\u00e9 confi\u00e9es comme Visiteur auxiliaire, et nous demandons \u00e0 Saint Jean-Baptiste de La Salle de continuer \u00e0 interc\u00e9der pour lui et pour le District de Lwanga.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":126631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_tec_requires_first_save":true,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","footnotes":""},"categories":[3368,3463,3302],"tags":[],"class_list":["post-126635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-relaf-fr","category-superieur-general"],"_links":{"self":[{"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/posts\/126635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/comments?post=126635"}],"version-history":[{"count":1,"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/posts\/126635\/revisions"}],"predecessor-version":[{"id":126636,"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/posts\/126635\/revisions\/126636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/media\/126631"}],"wp:attachment":[{"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/media?parent=126635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/categories?post=126635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasalle.org\/fr\/wp-json\/wp\/v2\/tags?post=126635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}